{"id":4798,"date":"2023-11-16T12:15:45","date_gmt":"2023-11-16T10:15:45","guid":{"rendered":"https:\/\/essecookers.nl\/?post_type=producten&#038;p=4798"},"modified":"2026-04-26T16:54:29","modified_gmt":"2026-04-26T14:54:29","slug":"esse-1000-w","status":"publish","type":"producten","link":"https:\/\/essecookers.nl\/be\/modellen\/esse-1000-w","title":{"rendered":"ESSE 1000 W"},"excerpt":{"rendered":"","protected":false},"featured_media":4797,"template":"","categories":[116],"tags":[123,112],"kleuren":[],"class_list":["post-4798","producten","type-producten","status-publish","has-post-thumbnail","hentry","category-houtfornuis","tag-om-te-koken-be","tag-om-te-verwarmen-be"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESSE 1000 W - ESSE Benelux<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESSE 1000 W - ESSE Benelux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798\" \/>\n<meta property=\"og:site_name\" content=\"ESSE Benelux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/essecooker.nl\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-26T14:54:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/essecookers.nl\/wp-content\/uploads\/2023\/11\/1000-W-Anthracite.png?wsr\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"966\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/essecookers.nl\\\/be\\\/wp-json\\\/wp\\\/v2\\\/producten\\\/4798\",\"url\":\"https:\\\/\\\/essecookers.nl\\\/be\\\/wp-json\\\/wp\\\/v2\\\/producten\\\/4798\",\"name\":\"Bookmarks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/essecookers.nl\\\/be#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/essecookers.nl\\\/be\\\/modellen\\\/esse-1000-w#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/essecookers.nl\\\/be\\\/modellen\\\/esse-1000-w#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/essecookers.nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1000-W-Anthracite.png?wsr\",\"datePublished\":\"2023-11-16T10:15:45+00:00\",\"dateModified\":\"2026-04-26T14:54:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/essecookers.nl\\\/be\\\/wp-json\\\/wp\\\/v2\\\/producten\\\/4798#breadcrumb\"},\"inLanguage\":\"be-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/essecookers.nl\\\/be\\\/modellen\\\/esse-1000-w\"]}],\"description\":null},{\"@type\":\"ImageObject\",\"inLanguage\":\"be-NL\",\"@id\":\"https:\\\/\\\/essecookers.nl\\\/be\\\/modellen\\\/esse-1000-w#primaryimage\",\"url\":\"https:\\\/\\\/essecookers.nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1000-W-Anthracite.png?wsr\",\"contentUrl\":\"https:\\\/\\\/essecookers.nl\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/1000-W-Anthracite.png?wsr\",\"width\":696,\"height\":966},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/essecookers.nl\\\/be\\\/wp-json\\\/wp\\\/v2\\\/producten\\\/4798#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/essecookers.nl\\\/be\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ESSE 1000 W\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/essecookers.nl\\\/be#website\",\"url\":\"https:\\\/\\\/essecookers.nl\\\/be\",\"name\":\"ESSE Nederland\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/essecookers.nl\\\/be?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"be-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESSE 1000 W - ESSE Benelux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798","og_locale":"en_US","og_type":"article","og_title":"ESSE 1000 W - ESSE Benelux","og_url":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798","og_site_name":"ESSE Benelux","article_publisher":"https:\/\/www.facebook.com\/essecooker.nl","article_modified_time":"2026-04-26T14:54:29+00:00","og_image":[{"width":696,"height":966,"url":"https:\/\/essecookers.nl\/wp-content\/uploads\/2023\/11\/1000-W-Anthracite.png?wsr","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798","url":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798","name":"Bookmarks","isPartOf":{"@id":"https:\/\/essecookers.nl\/be#website"},"primaryImageOfPage":{"@id":"https:\/\/essecookers.nl\/be\/modellen\/esse-1000-w#primaryimage"},"image":{"@id":"https:\/\/essecookers.nl\/be\/modellen\/esse-1000-w#primaryimage"},"thumbnailUrl":"https:\/\/essecookers.nl\/wp-content\/uploads\/2023\/11\/1000-W-Anthracite.png?wsr","datePublished":"2023-11-16T10:15:45+00:00","dateModified":"2026-04-26T14:54:29+00:00","breadcrumb":{"@id":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798#breadcrumb"},"inLanguage":"be-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/essecookers.nl\/be\/modellen\/esse-1000-w"]}],"description":null},{"@type":"ImageObject","inLanguage":"be-NL","@id":"https:\/\/essecookers.nl\/be\/modellen\/esse-1000-w#primaryimage","url":"https:\/\/essecookers.nl\/wp-content\/uploads\/2023\/11\/1000-W-Anthracite.png?wsr","contentUrl":"https:\/\/essecookers.nl\/wp-content\/uploads\/2023\/11\/1000-W-Anthracite.png?wsr","width":696,"height":966},{"@type":"BreadcrumbList","@id":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/essecookers.nl\/be"},{"@type":"ListItem","position":2,"name":""},{"@type":"ListItem","position":3,"name":"ESSE 1000 W"}]},{"@type":"WebSite","@id":"https:\/\/essecookers.nl\/be#website","url":"https:\/\/essecookers.nl\/be","name":"ESSE Nederland","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/essecookers.nl\/be?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"be-NL"}]}},"_links":{"self":[{"href":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten\/4798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/producten"}],"about":[{"href":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/types\/producten"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/media\/4797"}],"wp:attachment":[{"href":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/media?parent=4798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/categories?post=4798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/tags?post=4798"},{"taxonomy":"kleuren","embeddable":true,"href":"https:\/\/essecookers.nl\/be\/wp-json\/wp\/v2\/kleuren?post=4798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}